{"id":1244,"count":1,"description":"","link":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/","name":"peak-end rule","slug":"peak-end-rule","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>peak-end rule Archives - Debatrix\u00ae Vergroot je overtuigingskracht!<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"peak-end rule Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/\" \/>\n<meta property=\"og:site_name\" content=\"Debatrix\u00ae Vergroot je overtuigingskracht!\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/tag\\\/peak-end-rule\\\/\",\"url\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/tag\\\/peak-end-rule\\\/\",\"name\":\"peak-end rule Archives - Debatrix\u00ae Vergroot je overtuigingskracht!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/tag\\\/peak-end-rule\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/tag\\\/peak-end-rule\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"peak-end rule\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/\",\"name\":\"Debatrix\u00ae Vergroot je overtuigingskracht!\",\"description\":\"Alles over overtuigingskracht, presenteren, training en coaching\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.debatrix.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"peak-end rule Archives - Debatrix\u00ae Vergroot je overtuigingskracht!","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"peak-end rule Archives","og_url":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/","og_site_name":"Debatrix\u00ae Vergroot je overtuigingskracht!","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/","url":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/","name":"peak-end rule Archives - Debatrix\u00ae Vergroot je overtuigingskracht!","isPartOf":{"@id":"https:\/\/www.debatrix.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.debatrix.com\/nl\/tag\/peak-end-rule\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.debatrix.com\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"peak-end rule"}]},{"@type":"WebSite","@id":"https:\/\/www.debatrix.com\/nl\/#website","url":"https:\/\/www.debatrix.com\/nl\/","name":"Debatrix\u00ae Vergroot je overtuigingskracht!","description":"Alles over overtuigingskracht, presenteren, training en coaching","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.debatrix.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.debatrix.com\/nl\/wp-json\/wp\/v2\/tags\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debatrix.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.debatrix.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.debatrix.com\/nl\/wp-json\/wp\/v2\/posts?tags=1244"},{"href":"https:\/\/www.debatrix.com\/nl\/wp-json\/wp\/v2\/portfolio?tags=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}